{"id":2822,"date":"2026-06-10T23:43:12","date_gmt":"2026-06-10T21:43:12","guid":{"rendered":"https:\/\/mellelilyjolie.com\/?post_type=product&#038;p=2822"},"modified":"2026-06-21T00:24:48","modified_gmt":"2026-06-20T22:24:48","slug":"tee-shirt-femme-63","status":"publish","type":"product","link":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/","title":{"rendered":"TOTE BAG -MERCI MAITRESSE"},"content":{"rendered":"<p>La densit\u00e9 du <span title=\"Fibres r\u00e9colt\u00e9es au sein des gousses de cotonnier. Elles mesurent entre 5 et 10 cm de long et peuvent \u00eatre fil\u00e9es en fils, lesquels sont ensuite tiss\u00e9s dans des tissus en coton.\" data-toggle=\"tooltip\" data-placement=\"right\">coton<\/span>\u00a0de 140 g\/m\u00b2 rend le sac robuste, durable et adapt\u00e9 au transport d&rsquo;articles lourds dans le compartiment principal. Avec ses poign\u00e9es de 30 cm de long, ce sac fourre-tout est facile \u00e0 transporter.<\/p>\n<p>Entretien : Lavable en machine 30\u00b0 pour un entretien facile et repassage \u00e0 l&rsquo;envers \u00e0 temp\u00e9rature mod\u00e9r\u00e9. Notre tote bag est con\u00e7u pour r\u00e9sister aux usages quotidiens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le cadeau parfait pour remercier ma\u00eetresses, ma\u00eetres et nounous en fin d&rsquo;ann\u00e9e scolaire. Un tote bag personnalis\u00e9, pratique et plein de douceur, pour garder un joli souvenir de cette ann\u00e9e pass\u00e9e aupr\u00e8s de vos enfants.<\/p>\n<p>Exp\u00e9di\u00e9 dans un d\u00e9lai de 7 \u00e0 10 jours ouvrables<\/p>\n","protected":false},"featured_media":2823,"comment_status":"open","ping_status":"closed","template":"","meta":{"_surecart_dashboard_logo_width":"180px","_surecart_dashboard_show_logo":true,"_surecart_dashboard_navigation_orders":true,"_surecart_dashboard_navigation_invoices":true,"_surecart_dashboard_navigation_subscriptions":true,"_surecart_dashboard_navigation_downloads":true,"_surecart_dashboard_navigation_billing":true,"_surecart_dashboard_navigation_account":true,"_uag_custom_page_level_css":""},"product_brand":[],"product_cat":[276,270],"product_tag":[],"class_list":["post-2822","product","type-product","status-publish","has-post-thumbnail","product_cat-fin-dannee-scolaire-2","product_cat-idees-cadeaux-originaux-personnalises-melle-lily-jolie","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TOTE BAG -MERCI MAITRESSE &#8212; Melle Lily Jolie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TOTE BAG -MERCI MAITRESSE &#8212; Melle Lily Jolie\" \/>\n<meta property=\"og:description\" content=\"Le cadeau parfait pour remercier ma\u00eetresses, ma\u00eetres et nounous en fin d&#039;ann\u00e9e scolaire. Un tote bag personnalis\u00e9, pratique et plein de douceur, pour garder un joli souvenir de cette ann\u00e9e pass\u00e9e aupr\u00e8s de vos enfants.  Exp\u00e9di\u00e9 dans un d\u00e9lai de 7 \u00e0 10 jours ouvrables\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/\" \/>\n<meta property=\"og:site_name\" content=\"Melle Lily Jolie\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-20T22:24:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/produit\\\/tee-shirt-femme-63\\\/\",\"url\":\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/produit\\\/tee-shirt-femme-63\\\/\",\"name\":\"TOTE BAG -MERCI MAITRESSE &#8212; Melle Lily Jolie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/produit\\\/tee-shirt-femme-63\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/produit\\\/tee-shirt-femme-63\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mellelilyjolie.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png\",\"datePublished\":\"2026-06-10T21:43:12+00:00\",\"dateModified\":\"2026-06-20T22:24:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/produit\\\/tee-shirt-femme-63\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/produit\\\/tee-shirt-femme-63\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/produit\\\/tee-shirt-femme-63\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mellelilyjolie.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png\",\"contentUrl\":\"https:\\\/\\\/mellelilyjolie.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png\",\"width\":1414,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/produit\\\/tee-shirt-femme-63\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mellelilyjolie.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/mellelilyjolie.com\\\/index.php\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TOTE BAG -MERCI MAITRESSE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/#website\",\"url\":\"https:\\\/\\\/mellelilyjolie.com\\\/\",\"name\":\"Melle Lily Jolie\",\"description\":\"Cr\u00e9ations wax &amp; personnalisation fait main\",\"publisher\":{\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/#organization\"},\"alternateName\":\"MLJ Cr\u00e9ations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mellelilyjolie.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/#organization\",\"name\":\"Melle Lily Jolie\",\"alternateName\":\"MLJ Cr\u00e9ations\",\"url\":\"https:\\\/\\\/mellelilyjolie.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mellelilyjolie.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/ChatGPT-Image-22-juin-2026-00_18_29.png\",\"contentUrl\":\"https:\\\/\\\/mellelilyjolie.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/ChatGPT-Image-22-juin-2026-00_18_29.png\",\"width\":1254,\"height\":1254,\"caption\":\"Melle Lily Jolie\"},\"image\":{\"@id\":\"https:\\\/\\\/mellelilyjolie.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/melle_lily_jolie\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TOTE BAG -MERCI MAITRESSE &#8212; Melle Lily Jolie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/","og_locale":"fr_FR","og_type":"article","og_title":"TOTE BAG -MERCI MAITRESSE &#8212; Melle Lily Jolie","og_description":"Le cadeau parfait pour remercier ma\u00eetresses, ma\u00eetres et nounous en fin d'ann\u00e9e scolaire. Un tote bag personnalis\u00e9, pratique et plein de douceur, pour garder un joli souvenir de cette ann\u00e9e pass\u00e9e aupr\u00e8s de vos enfants.  Exp\u00e9di\u00e9 dans un d\u00e9lai de 7 \u00e0 10 jours ouvrables","og_url":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/","og_site_name":"Melle Lily Jolie","article_modified_time":"2026-06-20T22:24:48+00:00","og_image":[{"width":1414,"height":2000,"url":"https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/","url":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/","name":"TOTE BAG -MERCI MAITRESSE &#8212; Melle Lily Jolie","isPartOf":{"@id":"https:\/\/mellelilyjolie.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/#primaryimage"},"image":{"@id":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/#primaryimage"},"thumbnailUrl":"https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png","datePublished":"2026-06-10T21:43:12+00:00","dateModified":"2026-06-20T22:24:48+00:00","breadcrumb":{"@id":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/#primaryimage","url":"https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png","contentUrl":"https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png","width":1414,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/mellelilyjolie.com\/index.php\/produit\/tee-shirt-femme-63\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mellelilyjolie.com\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/mellelilyjolie.com\/index.php\/shop\/"},{"@type":"ListItem","position":3,"name":"TOTE BAG -MERCI MAITRESSE"}]},{"@type":"WebSite","@id":"https:\/\/mellelilyjolie.com\/#website","url":"https:\/\/mellelilyjolie.com\/","name":"Melle Lily Jolie","description":"Cr\u00e9ations wax &amp; personnalisation fait main","publisher":{"@id":"https:\/\/mellelilyjolie.com\/#organization"},"alternateName":"MLJ Cr\u00e9ations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mellelilyjolie.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mellelilyjolie.com\/#organization","name":"Melle Lily Jolie","alternateName":"MLJ Cr\u00e9ations","url":"https:\/\/mellelilyjolie.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mellelilyjolie.com\/#\/schema\/logo\/image\/","url":"https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-22-juin-2026-00_18_29.png","contentUrl":"https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-22-juin-2026-00_18_29.png","width":1254,"height":1254,"caption":"Melle Lily Jolie"},"image":{"@id":"https:\/\/mellelilyjolie.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/melle_lily_jolie"]}]}},"uagb_featured_image_src":{"full":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png",1414,2000,false],"thumbnail":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-150x150.png",150,150,true],"medium":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-212x300.png",212,300,true],"medium_large":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-768x1086.png",768,1086,true],"large":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-724x1024.png",724,1024,true],"post-slider-thumb-size":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-330x190.png",330,190,true],"post-category-slider-size":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-330x350.png",330,350,true],"1536x1536":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-1086x1536.png",1086,1536,true],"2048x2048":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308.png",1414,2000,false],"ashe-slider-full-thumbnail":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-1080x540.png",1080,540,true],"ashe-full-thumbnail":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-1140x1612.png",1140,1612,true],"ashe-list-thumbnail":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-300x300.png",300,300,true],"ashe-grid-thumbnail":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-500x330.png",500,330,true],"ashe-single-navigation":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-75x75.png",75,75,true],"woocommerce_thumbnail":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-300x300.png",300,300,true],"woocommerce_single":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-600x849.png",600,849,true],"woocommerce_gallery_thumbnail":["https:\/\/mellelilyjolie.com\/wp-content\/uploads\/2026\/06\/livret-collection-MANJACK-BY-MLJ-2026-06-10T233309.308-100x100.png",100,100,true]},"uagb_author_info":{"display_name":"admin7170","author_link":"https:\/\/mellelilyjolie.com\/index.php\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Le cadeau parfait pour remercier ma\u00eetresses, ma\u00eetres et nounous en fin d'ann\u00e9e scolaire. Un tote bag personnalis\u00e9, pratique et plein de douceur, pour garder un joli souvenir de cette ann\u00e9e pass\u00e9e aupr\u00e8s de vos enfants. Exp\u00e9di\u00e9 dans un d\u00e9lai de 7 \u00e0 10 jours ouvrables","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/product\/2822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/comments?post=2822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/media\/2823"}],"wp:attachment":[{"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/media?parent=2822"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=2822"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=2822"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mellelilyjolie.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=2822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}